{"id":68775,"date":"2017-05-10T00:24:48","date_gmt":"2017-05-10T00:24:48","guid":{"rendered":"http:\/\/galapagosinformation.com\/blog\/?p=68775"},"modified":"2017-05-10T01:06:25","modified_gmt":"2017-05-10T01:06:25","slug":"croisieres-aux-iles-galapagos-en-juillet","status":"publish","type":"post","link":"https:\/\/galapagosinformation.com\/blog\/croisieres-aux-iles-galapagos-en-juillet\/","title":{"rendered":"Croisi\u00e8res aux \u00celes Gal\u00e1pagos en Juillet"},"content":{"rendered":"<p>Voici tout ce que vous avez besoin de savoir pour planifier le plus spectaculaire des voyages que vous pouvez imaginer : Gal\u00e1pagos Tout Inclus.\u00a0<strong>Croisi\u00e8res aux \u00celes Gal\u00e1pagos en Juillet<\/strong>.<\/p>\n<p>Catamarans en offre aux \u00celes Gal\u00e1pagos. Vous avez envie de voyager \u00e0 un des plus beaux sites de la plan\u00e8te ? Sur notre site web, son list\u00e9es toutes les options pour vivre une exp\u00e9rience unique.<\/p>\n<p>En termes de climat, les \u00celes Gal\u00e1pagos pr\u00e9sentent deux saisons clairement distinctes. La saison des pluies de Janvier \u00e0 Mai, avec des temp\u00e9ratures moyennes comprises entre 23\u00b0 et 27\u00b0, et une saison s\u00e8che de Juin et D\u00e9cembre, avec une moyenne de 19\u00b0. La monnaie officielle est le dollar am\u00e9ricain (USD), ce qui est important \u00e0 savoir pour ne pas changer tout votre argent \u00e0 l\u2019a\u00e9roport.<\/p>\n<p>Si vous souhaitez un bref r\u00e9sum\u00e9 de ce que vous pourrez trouver en parcourant les \u00celes Gal\u00e1pagos \u00e0 bord d\u2019une croisi\u00e8re tout inclus, nous vous montrons une s\u00e9rie d\u2019endroits qui peuvent \u00eatre parcourus. Si vous avez des questions sur le voyage et sa dur\u00e9e, n\u2019h\u00e9sitez pas \u00e0 nous contacter.<\/p>\n<p><strong>Baie Gardner sur l\u2019\u00cele Espa\u00f1ola <\/strong>: Baie Gardner est une des incroyables plages qui se trouvent sur l\u2019archipel, avec une \u00e9tendue de plus d\u2019un kilom\u00e8tre de sable blanc et d\u2019eau turquoise, appr\u00e9ci\u00e9e par les colonies d\u2019otaries qui ont l\u2019habitude de batifoler \u00e0 quelques m\u00e8tres de l\u2019eau. Comme tous les endroits des Gal\u00e1pagos, nous avons la possibilit\u00e9 de profiter de la biodiversit\u00e9 des oiseaux qui parcourent le secteur, et notamment de trois vari\u00e9t\u00e9s uniques d\u2019oiseaux de Darwin.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-68789\" src=\"http:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-Juillet.jpg\" alt=\"\" width=\"620\" height=\"414\" srcset=\"https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-Juillet.jpg 620w, https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-Juillet-300x200.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p><strong>\u00cele de San Crist\u00f3bal <\/strong>: Sans l\u2019ombre d\u2019un doute, c\u2019est un des endroits les plus divertissants des Gal\u00e1pagos, dont les c\u00f4tes abritent quelques-unes des plus grandes colonies de tortues de l\u2019archipel. Au Sud-Est de San Crist\u00f3bal, se situe la Galapaguera de Cerro Colorado, un projet de sauvetage de tortues gigantesques qui permet de se trouver \u00e0 quelques pas de ces magnifiques cr\u00e9atures qui, durant leurs deux premi\u00e8res ann\u00e9es, grandissent en captivit\u00e9. Vers le secteur Nord-Est, se trouve la Galapaguera Natural, un espace o\u00f9 il est possible de voir des tortues dans leur environnement naturel, aussi bien sur la plage m\u00eame o\u00f9 ils nichent que sur les dunes de sable o\u00f9 ils pondent. Une zone d\u2019\u00e9norme beaut\u00e9 est La Lober\u00eda, plage de sable corallien o\u00f9 se reposent les phoques et les iguanes marins, alors que les oiseaux comme le canari, la fr\u00e9gate et plusieurs esp\u00e8ces de pinsons survolent la zone.<\/p>\n<p>[enlace_dinamico_fr]<\/p>\n<p>Sur sa c\u00f4te occidentale se trouve Puerto Baquerizo Moreno, le plus important secteur habit\u00e9 de San Crist\u00f3bal et le deuxi\u00e8me de l\u2019archipel, lieu o\u00f9 il est possible de trouver une importante offre h\u00f4teli\u00e8re, de restaurants et a\u00e9roportuaire. Le second endroit le plus visit\u00e9 est la Baie Gardner, une plage reconnue pour sa beaut\u00e9, o\u00f9 vit une importante colonie de phoques qui se reposent sur le sable.<\/p>\n<p><strong>Ilot Seymour Norte <\/strong>: Avec une abondante v\u00e9g\u00e9tation basse et dense, elle fascine pour sa nature presque immacul\u00e9e, condition qui r\u00e9sulte plus difficile \u00e0 trouver sur les \u00celes de plus grande taille. Le parcours s\u2019effectue sur la base d\u2019un chemin de 2 kilom\u00e8tres de long qui traverse l\u2019ilot de bout en bout, et qui permet de croiser des fr\u00e9gates, des iguanes terrestres et des otaries.<\/p>\n<h2>Environnement<\/h2>\n<p>Sur les croisi\u00e8res, il existe la possibilit\u00e9 de voir et de marcher vers l\u2019habitat d\u2019esp\u00e8ces animales qui se sont cach\u00e9es durant des si\u00e8cles, avec une diversit\u00e9 incroyable et totalement immacul\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voici tout ce que vous avez besoin de savoir pour planifier le plus spectaculaire des voyages que vous pouvez imaginer : Gal\u00e1pagos Tout Inclus.\u00a0Croisi\u00e8res aux \u00celes Gal\u00e1pagos en Juillet. Catamarans en offre aux \u00celes Gal\u00e1pagos. Vous avez envie de voyager \u00e0 un des plus beaux sites de la plan\u00e8te ? Sur notre site web, son list\u00e9es toutes les options pour vivre une exp\u00e9rience unique. En termes de climat, les \u00celes Gal\u00e1pagos pr\u00e9sentent deux saisons clairement distinctes. La saison des pluies de Janvier \u00e0 Mai, avec des temp\u00e9ratures moyennes comprises entre 23\u00b0 et 27\u00b0, et une saison s\u00e8che de Juin et D\u00e9cembre, avec une moyenne de 19\u00b0. La monnaie officielle est le dollar am\u00e9ricain (USD), ce qui est important \u00e0 savoir pour ne pas changer tout votre argent \u00e0 l\u2019a\u00e9roport. Si vous souhaitez un bref r\u00e9sum\u00e9 de ce que vous pourrez trouver en parcourant les \u00celes Gal\u00e1pagos \u00e0 bord d\u2019une croisi\u00e8re tout inclus, nous vous montrons une s\u00e9rie d\u2019endroits qui peuvent \u00eatre parcourus. Si vous avez des questions sur le voyage et sa dur\u00e9e, n\u2019h\u00e9sitez pas \u00e0 nous contacter. Baie Gardner sur l\u2019\u00cele Espa\u00f1ola : Baie Gardner est une des incroyables plages qui se trouvent sur l\u2019archipel, avec une \u00e9tendue de plus d\u2019un kilom\u00e8tre de sable blanc et d\u2019eau turquoise, appr\u00e9ci\u00e9e par les colonies d\u2019otaries qui ont l\u2019habitude de batifoler \u00e0 quelques m\u00e8tres de l\u2019eau. Comme tous les endroits des Gal\u00e1pagos, nous avons la possibilit\u00e9 de profiter de la biodiversit\u00e9 des oiseaux qui parcourent le secteur, et notamment de trois vari\u00e9t\u00e9s uniques d\u2019oiseaux de Darwin. \u00cele de San Crist\u00f3bal : Sans l\u2019ombre d\u2019un doute, c\u2019est un des endroits les plus divertissants des Gal\u00e1pagos, dont les c\u00f4tes abritent quelques-unes des plus grandes colonies de tortues de l\u2019archipel. Au Sud-Est de San Crist\u00f3bal, se situe la Galapaguera de Cerro Colorado, un projet de sauvetage de tortues gigantesques qui permet de se trouver \u00e0 quelques pas de ces magnifiques cr\u00e9atures qui, durant leurs deux premi\u00e8res ann\u00e9es, grandissent en captivit\u00e9. Vers le secteur Nord-Est, se trouve la Galapaguera Natural, un espace o\u00f9 il est possible de voir des tortues dans leur environnement naturel, aussi bien sur la plage m\u00eame o\u00f9 ils nichent que sur les dunes de sable o\u00f9 ils pondent. Une zone d\u2019\u00e9norme beaut\u00e9 est La Lober\u00eda, plage de sable corallien o\u00f9 se reposent les phoques et les iguanes marins, alors que les oiseaux comme le canari, la fr\u00e9gate et plusieurs esp\u00e8ces de pinsons survolent la zone. [enlace_dinamico_fr] Sur sa c\u00f4te occidentale se trouve Puerto Baquerizo Moreno, le plus important secteur habit\u00e9 de San Crist\u00f3bal et le deuxi\u00e8me de l\u2019archipel, lieu o\u00f9 il est possible de trouver une importante offre h\u00f4teli\u00e8re, de restaurants et a\u00e9roportuaire. Le second endroit le plus visit\u00e9 est la Baie Gardner, une plage reconnue pour sa beaut\u00e9, o\u00f9 vit une importante colonie de phoques qui se reposent sur le sable. Ilot Seymour Norte : Avec une abondante v\u00e9g\u00e9tation basse et dense, elle fascine pour sa nature presque immacul\u00e9e, condition qui r\u00e9sulte plus difficile \u00e0 trouver sur les \u00celes de plus grande taille. Le parcours s\u2019effectue sur la base d\u2019un chemin de 2 kilom\u00e8tres de long qui traverse l\u2019ilot de bout en bout, et qui permet de croiser des fr\u00e9gates, des iguanes terrestres et des otaries. Environnement Sur les croisi\u00e8res, il existe la possibilit\u00e9 de voir et de marcher vers l\u2019habitat d\u2019esp\u00e8ces animales qui se sont cach\u00e9es durant des si\u00e8cles, avec une diversit\u00e9 incroyable et totalement immacul\u00e9e.<\/p>\n","protected":false},"author":1,"featured_media":68789,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[22,21],"tags":[],"class_list":["post-68775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-croisieres-aux-iles-galapagos","category-francais"],"aioseo_notices":[],"spectra_custom_meta":{"_edit_lock":["1494378387:2"],"_edit_last":["2"],"post-option-sidebar-template":["right-sidebar"],"post-option-choose-left-sidebar":["lateral"],"post-option-choose-right-sidebar":["lateral"],"post-option-blog-header-title":[""],"post-option-blog-header-caption":[""],"post-option-author-info-enabled":["Yes"],"post-option-social-enabled":["Yes"],"post-option-thumbnail-types":["Image"],"post-option-thumbnail-video":[""],"post-option-thumbnail-xml":["<slider-item><\/slider-item>"],"post-option-thumbnail-html5-video":[""],"post-option-inside-thumbnail-types":["Image"],"post-option-inside-thumbnial-image":[""],"post-option-inside-thumbnail-video":[""],"post-option-inside-thumbnail-xml":["<slider-item><\/slider-item>"],"post-option-inside-thumbnail-html5-video":[""],"_thumbnail_id":["68789"],"_uag_css_file_name":["uag-css-68775.css"],"_uag_page_assets":["a:9:{s:3:\"css\";s:260:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:1:{i:0;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1778159567\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-Juillet.jpg",620,414,false],"thumbnail":["https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-Juillet-150x150.jpg",150,150,true],"medium":["https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-Juillet-300x200.jpg",218,145,true],"medium_large":["https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-Juillet.jpg",620,414,false],"large":["https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-Juillet.jpg",620,414,false],"1536x1536":["https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-Juillet-1536x1536.jpg",1536,1536,true],"2048x2048":["https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-Juillet-2048x2048.jpg",2048,2048,true]},"uagb_author_info":{"display_name":"Nemo Galapagos Cruises","author_link":"https:\/\/galapagosinformation.com\/blog\/author\/nemogalapagoscruises\/"},"uagb_comment_info":0,"uagb_excerpt":"Voici tout ce que vous avez besoin de savoir pour planifier le plus spectaculaire des voyages que vous pouvez imaginer : Gal\u00e1pagos Tout Inclus.\u00a0Croisi\u00e8res aux \u00celes Gal\u00e1pagos en Juillet. Catamarans en offre aux \u00celes Gal\u00e1pagos. Vous avez envie de voyager \u00e0 un des plus beaux sites de la plan\u00e8te ? Sur notre site web, son&hellip;","_links":{"self":[{"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/posts\/68775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/comments?post=68775"}],"version-history":[{"count":0,"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/posts\/68775\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/media\/68789"}],"wp:attachment":[{"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/media?parent=68775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/categories?post=68775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/tags?post=68775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}