{"id":68780,"date":"2017-05-10T00:44:17","date_gmt":"2017-05-10T00:44:17","guid":{"rendered":"http:\/\/galapagosinformation.com\/blog\/?p=68780"},"modified":"2017-05-10T00:51:14","modified_gmt":"2017-05-10T00:51:14","slug":"croisieres-aux-iles-galapagos-en-decembre","status":"publish","type":"post","link":"https:\/\/galapagosinformation.com\/blog\/croisieres-aux-iles-galapagos-en-decembre\/","title":{"rendered":"Croisi\u00e8res aux \u00celes Gal\u00e1pagos en D\u00e9cembre"},"content":{"rendered":"<p>Les meilleurs endroits pour visiter et parcourir les incroyables \u00celes Gal\u00e1pagos.\u00a0<strong>Croisi\u00e8res aux \u00celes Gal\u00e1pagos en D\u00e9cembre<\/strong>.<\/p>\n<p>Les \u00eeles Gal\u00e1pagos sont le produit d\u2019\u00e9ruptions volcaniques en continue. Par leur localisation unique, elles ont d\u00e9velopp\u00e9 des esp\u00e8ces uniques au monde, d\u2019une richesse tr\u00e8s difficile \u00e0 croire. C\u2019est pour cela qu\u2019elles sont un des endroits favoris de tous les voyageurs amoureux des esp\u00e8ces sauvages.<\/p>\n<p>En r\u00e8gle g\u00e9n\u00e9rale, il existe deux saisons. La premi\u00e8re saison qui va de D\u00e9cembre \u00e0 Juin s\u2019appelle Saison Chaude. Et la deuxi\u00e8me saison qui va de Juin \u00e0 Novembre s\u2019appelle Saison S\u00e8che. Le meilleur moment pour tirer profit des \u00celes Gal\u00e1pagos est durant les mois de transition. Cependant, n\u2019importe quel mois de l\u2019ann\u00e9e est bien pour visiter les \u00eeles, puisqu\u2019il n\u2019y a aucun mois durant lequel le climat des Gal\u00e1pagos est insupportable ou sans faune et flore int\u00e9ressante \u00e0 observer. Face \u00e0 deux saisons aussi diff\u00e9rentes l\u2019une de l\u2019autre, marquant le d\u00e9but et la fin de la p\u00e9riode d\u2019accouplement pour la majorit\u00e9 des esp\u00e8ces, il y a quelques mois durant lesquels les deux saisons peuvent \u00eatre pr\u00e9sentent en m\u00eame temps. Se pr\u00e9sente d\u2019abord un changement entre la saison chaude et la saison s\u00e8che, puis une transition entre la saison s\u00e8che et la saison chaude (Novembre \u00e0 Janvier).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-68781\" src=\"http:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-D\u00e9cembre.jpg\" alt=\"\" width=\"620\" height=\"414\" srcset=\"https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-D\u00e9cembre.jpg 620w, https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-D\u00e9cembre-300x200.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Vous ne savez pas quoi faire aux \u00celes Gal\u00e1pagos ? Cela n\u2019est pas un probl\u00e8me ! En r\u00e9servant un voyage pour les \u00eeles, vous pouvez passer jusqu\u2019\u00e0 deux semaines \u00e0 conna\u00eetre toutes les beaut\u00e9s naturelles que cet agr\u00e9able endroit d\u2019\u00c9quateur peut vous offrir. Les voyages tout inclus peuvent \u00eatre r\u00e9serv\u00e9s en ligne avec jusqu\u2019\u00e0 un mois d\u2019anticipation, avec l\u2019option de paiement par carte ou par virement bancaire.<\/p>\n<p><strong>\u00cele Genovesa<\/strong>: Genovesa est aussi connue comme l\u2019\u00cele Tower et est consid\u00e9r\u00e9e par beaucoup de ses visiteurs comme l\u2019\u00eele la plus attirante de toutes. Son nom provient de la ville de G\u00e9nova (en Italie) o\u00f9 il se dit qu\u2019elle serait le lieu de naissance de Christophe Colomb. C\u2019est un endroit id\u00e9al pour les observateurs d\u2019oiseaux car ces derniers sont pr\u00e9sents en quantit\u00e9 abondante, parmi lesquelles quelques esp\u00e8ces comme la mouette \u00e0 deux pointes ou la mouette de lave, les uniques mouettes qui ont des habitudes de chasse nocturne. L\u2019\u00eele Genovesa est un volcan \u00e9teint, qui a \u00e9t\u00e9 victime de nombreux glissements de terrain caus\u00e9s par son activit\u00e9 volcanique. Deux sites peuvent en permettre la visite, \u00e0 partir d\u2019une br\u00e8che qui se trouve aux pieds du volcan. Il y a des milliers d\u2019ann\u00e9es, c\u2019\u00e9tait un gigantesque volcan dont le c\u00f4t\u00e9 Sud s\u2019est effondr\u00e9, formant la Grande Baie de Darwin, lieu o\u00f9 actuellement un grand nombre d\u2019oiseaux font leur nid. Au centre de l\u2019\u00cele Genevesa se trouve le lac Arcturus, rempli d\u2019eau sal\u00e9e, endroit o\u00f9 vit le plus petit iguane marin de l\u2019archipel.<\/p>\n<p>[enlace_dinamico_fr]<\/p>\n<p>De m\u00eame mani\u00e8re, il est possible de trouver des phoques et une grande for\u00eat de Palo Santo. Sur la Baie Darwin peut \u00eatre pratiqu\u00e9e la plong\u00e9e sur les parois internes et externes. Genovesa abrite une grande quantit\u00e9 d\u2019oiseaux p\u00e9lagiques (de l\u2019oc\u00e9an), qui viennent faire leur nid et se reproduire sur cette \u00eele, parmi lesquelles ont compte d\u2019\u00e9normes fr\u00e9gates, des fous \u00e0 pieds bleus, des mouettes de frac, des oiseaux tropicaux, des pinsons de Darwin et des p\u00e9trels.<\/p>\n<p><strong>Le\u00f3n Dormido sur l\u2019\u00cele San Crist\u00f3bal:\u00a0<\/strong>\u00c9galement appel\u00e9 Kicker Rock, il correspond \u00e0 deux \u00e9normes roches volcaniques avec une altitude de plus de 100 m\u00e8tres au-dessus du niveau de la mer. Accessible par la mer depuis Puerto Baquerizo, son curieux nom vient de sa similitude avec un lion endormi, en le voyant de loin. Cet endroit est des plus c\u00e9l\u00e8bres secteurs touristiques des Gal\u00e1pagos pour faire de la plong\u00e9e, ou pour nager entour\u00e9 de raies Manta, de requins, d\u2019otaries et de poissons. Ses roches aiguis\u00e9es sont aussi la maison d\u2019\u00e9normes colonies d\u2019oiseaux, comme le fou \u00e0 pattes bleues, la fr\u00e9gate et le p\u00e9lican.<\/p>\n<p><strong>\u00cele Santa Fe<\/strong>: \u00cele inhabit\u00e9e par l\u2019homme, connue pour ses plages d\u2019eaux calmes sur la Baie Barrington, endroit o\u00f9 on peut aussi bien se reposer sur le sable o\u00f9 abondent des otaries que s\u2019immerger en plongeant. Si les animaux vous int\u00e9ressent, vous pourrez voir de g\u00e9ants iguanes terrestres, animaux se trouvant uniquement sur cette \u00eele et qui peuvent mesurer jusqu\u2019\u00e0 un m\u00e8tre de long.<\/p>\n<p><strong>Cerro Drag\u00f3n<\/strong>: Son nom est d\u00fb \u00e0 l\u2019ann\u00e9e 1975, lorsqu\u2019il \u00e9tait un des seuls endroits de l\u2019\u00cele Santa Cruz o\u00f9 se trouvaient des iguanes terrestres en abondance. Cet endroit a \u00e9t\u00e9 l\u2019objet de multiples efforts pour prot\u00e9ger les colonies d\u2019iguanes, pour assurer leur reproduction. Au jour d\u2019aujourd\u2019hui, il n\u2019existe plus de chiens sauvages \u00e0 Cerro Drag\u00f3n, bien que le Parc National Gal\u00e1pagos r\u00e9alise des contr\u00f4les constants d\u2019autres animaux qui peuvent \u00eatre dangereux. Dans les lagons pr\u00e9sents \u00e0 cet endroit, vivent les crevettes, l\u2019aliment m\u00eame des flamands roses. A certaines \u00e9poques de l\u2019ann\u00e9e, elles sont pr\u00e9sentes en plus grand nombre. Pour cette raison, la population des oiseaux est plus importante. Par saison des pluies, l\u2019eau devient trop douce, la population de crustac\u00e9s diminue donc, ce qui entra\u00eene une baisse de la quantit\u00e9 d\u2019oiseaux. Cerro Drag\u00f3n est ouvert au public depuis l\u2019ann\u00e9e 1993. La plage contient des formations rocheuses. En mar\u00e9e haute, c\u2019est un bon endroit pour faire de la plonger \u00e0 la surface.<\/p>\n<h3>Environnement<\/h3>\n<p>Dans nos voyages tout inclus, nous pouvons observer et nous approcher de l\u2019habitat des esp\u00e8ces animales qui ont \u00e9t\u00e9 cach\u00e9es pour des centaines d\u2019ann\u00e9es, avec une diversit\u00e9 incroyable et presque immacul\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les meilleurs endroits pour visiter et parcourir les incroyables \u00celes Gal\u00e1pagos.\u00a0Croisi\u00e8res aux \u00celes Gal\u00e1pagos en D\u00e9cembre. Les \u00eeles Gal\u00e1pagos sont le produit d\u2019\u00e9ruptions volcaniques en continue. Par leur localisation unique, elles ont d\u00e9velopp\u00e9 des esp\u00e8ces uniques au monde, d\u2019une richesse tr\u00e8s difficile \u00e0 croire. C\u2019est pour cela qu\u2019elles sont un des endroits favoris de tous les voyageurs amoureux des esp\u00e8ces sauvages. En r\u00e8gle g\u00e9n\u00e9rale, il existe deux saisons. La premi\u00e8re saison qui va de D\u00e9cembre \u00e0 Juin s\u2019appelle Saison Chaude. Et la deuxi\u00e8me saison qui va de Juin \u00e0 Novembre s\u2019appelle Saison S\u00e8che. Le meilleur moment pour tirer profit des \u00celes Gal\u00e1pagos est durant les mois de transition. Cependant, n\u2019importe quel mois de l\u2019ann\u00e9e est bien pour visiter les \u00eeles, puisqu\u2019il n\u2019y a aucun mois durant lequel le climat des Gal\u00e1pagos est insupportable ou sans faune et flore int\u00e9ressante \u00e0 observer. Face \u00e0 deux saisons aussi diff\u00e9rentes l\u2019une de l\u2019autre, marquant le d\u00e9but et la fin de la p\u00e9riode d\u2019accouplement pour la majorit\u00e9 des esp\u00e8ces, il y a quelques mois durant lesquels les deux saisons peuvent \u00eatre pr\u00e9sentent en m\u00eame temps. Se pr\u00e9sente d\u2019abord un changement entre la saison chaude et la saison s\u00e8che, puis une transition entre la saison s\u00e8che et la saison chaude (Novembre \u00e0 Janvier). Vous ne savez pas quoi faire aux \u00celes Gal\u00e1pagos ? Cela n\u2019est pas un probl\u00e8me ! En r\u00e9servant un voyage pour les \u00eeles, vous pouvez passer jusqu\u2019\u00e0 deux semaines \u00e0 conna\u00eetre toutes les beaut\u00e9s naturelles que cet agr\u00e9able endroit d\u2019\u00c9quateur peut vous offrir. Les voyages tout inclus peuvent \u00eatre r\u00e9serv\u00e9s en ligne avec jusqu\u2019\u00e0 un mois d\u2019anticipation, avec l\u2019option de paiement par carte ou par virement bancaire. \u00cele Genovesa: Genovesa est aussi connue comme l\u2019\u00cele Tower et est consid\u00e9r\u00e9e par beaucoup de ses visiteurs comme l\u2019\u00eele la plus attirante de toutes. Son nom provient de la ville de G\u00e9nova (en Italie) o\u00f9 il se dit qu\u2019elle serait le lieu de naissance de Christophe Colomb. C\u2019est un endroit id\u00e9al pour les observateurs d\u2019oiseaux car ces derniers sont pr\u00e9sents en quantit\u00e9 abondante, parmi lesquelles quelques esp\u00e8ces comme la mouette \u00e0 deux pointes ou la mouette de lave, les uniques mouettes qui ont des habitudes de chasse nocturne. L\u2019\u00eele Genovesa est un volcan \u00e9teint, qui a \u00e9t\u00e9 victime de nombreux glissements de terrain caus\u00e9s par son activit\u00e9 volcanique. Deux sites peuvent en permettre la visite, \u00e0 partir d\u2019une br\u00e8che qui se trouve aux pieds du volcan. Il y a des milliers d\u2019ann\u00e9es, c\u2019\u00e9tait un gigantesque volcan dont le c\u00f4t\u00e9 Sud s\u2019est effondr\u00e9, formant la Grande Baie de Darwin, lieu o\u00f9 actuellement un grand nombre d\u2019oiseaux font leur nid. Au centre de l\u2019\u00cele Genevesa se trouve le lac Arcturus, rempli d\u2019eau sal\u00e9e, endroit o\u00f9 vit le plus petit iguane marin de l\u2019archipel. [enlace_dinamico_fr] De m\u00eame mani\u00e8re, il est possible de trouver des phoques et une grande for\u00eat de Palo Santo. Sur la Baie Darwin peut \u00eatre pratiqu\u00e9e la plong\u00e9e sur les parois internes et externes. Genovesa abrite une grande quantit\u00e9 d\u2019oiseaux p\u00e9lagiques (de l\u2019oc\u00e9an), qui viennent faire leur nid et se reproduire sur cette \u00eele, parmi lesquelles ont compte d\u2019\u00e9normes fr\u00e9gates, des fous \u00e0 pieds bleus, des mouettes de frac, des oiseaux tropicaux, des pinsons de Darwin et des p\u00e9trels. Le\u00f3n Dormido sur l\u2019\u00cele San Crist\u00f3bal:\u00a0\u00c9galement appel\u00e9 Kicker Rock, il correspond \u00e0 deux \u00e9normes roches volcaniques avec une altitude de plus de 100 m\u00e8tres au-dessus du niveau de la mer. Accessible par la mer depuis Puerto Baquerizo, son curieux nom vient de sa similitude avec un lion endormi, en le voyant de loin. Cet endroit est des plus c\u00e9l\u00e8bres secteurs touristiques des Gal\u00e1pagos pour faire de la plong\u00e9e, ou pour nager entour\u00e9 de raies Manta, de requins, d\u2019otaries et de poissons. Ses roches aiguis\u00e9es sont aussi la maison d\u2019\u00e9normes colonies d\u2019oiseaux, comme le fou \u00e0 pattes bleues, la fr\u00e9gate et le p\u00e9lican. \u00cele Santa Fe: \u00cele inhabit\u00e9e par l\u2019homme, connue pour ses plages d\u2019eaux calmes sur la Baie Barrington, endroit o\u00f9 on peut aussi bien se reposer sur le sable o\u00f9 abondent des otaries que s\u2019immerger en plongeant. Si les animaux vous int\u00e9ressent, vous pourrez voir de g\u00e9ants iguanes terrestres, animaux se trouvant uniquement sur cette \u00eele et qui peuvent mesurer jusqu\u2019\u00e0 un m\u00e8tre de long. Cerro Drag\u00f3n: Son nom est d\u00fb \u00e0 l\u2019ann\u00e9e 1975, lorsqu\u2019il \u00e9tait un des seuls endroits de l\u2019\u00cele Santa Cruz o\u00f9 se trouvaient des iguanes terrestres en abondance. Cet endroit a \u00e9t\u00e9 l\u2019objet de multiples efforts pour prot\u00e9ger les colonies d\u2019iguanes, pour assurer leur reproduction. Au jour d\u2019aujourd\u2019hui, il n\u2019existe plus de chiens sauvages \u00e0 Cerro Drag\u00f3n, bien que le Parc National Gal\u00e1pagos r\u00e9alise des contr\u00f4les constants d\u2019autres animaux qui peuvent \u00eatre dangereux. Dans les lagons pr\u00e9sents \u00e0 cet endroit, vivent les crevettes, l\u2019aliment m\u00eame des flamands roses. A certaines \u00e9poques de l\u2019ann\u00e9e, elles sont pr\u00e9sentes en plus grand nombre. Pour cette raison, la population des oiseaux est plus importante. Par saison des pluies, l\u2019eau devient trop douce, la population de crustac\u00e9s diminue donc, ce qui entra\u00eene une baisse de la quantit\u00e9 d\u2019oiseaux. Cerro Drag\u00f3n est ouvert au public depuis l\u2019ann\u00e9e 1993. La plage contient des formations rocheuses. En mar\u00e9e haute, c\u2019est un bon endroit pour faire de la plonger \u00e0 la surface. Environnement Dans nos voyages tout inclus, nous pouvons observer et nous approcher de l\u2019habitat des esp\u00e8ces animales qui ont \u00e9t\u00e9 cach\u00e9es pour des centaines d\u2019ann\u00e9es, avec une diversit\u00e9 incroyable et presque immacul\u00e9e.<\/p>\n","protected":false},"author":1,"featured_media":68781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[22,21],"tags":[],"class_list":["post-68780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-croisieres-aux-iles-galapagos","category-francais"],"aioseo_notices":[],"spectra_custom_meta":{"_edit_lock":["1494377460:2"],"_edit_last":["2"],"post-option-sidebar-template":["right-sidebar"],"post-option-choose-left-sidebar":["lateral"],"post-option-choose-right-sidebar":["lateral"],"post-option-blog-header-title":[""],"post-option-blog-header-caption":[""],"post-option-author-info-enabled":["Yes"],"post-option-social-enabled":["Yes"],"post-option-thumbnail-types":["Image"],"post-option-thumbnail-video":[""],"post-option-thumbnail-xml":["<slider-item><\/slider-item>"],"post-option-thumbnail-html5-video":[""],"post-option-inside-thumbnail-types":["Image"],"post-option-inside-thumbnial-image":[""],"post-option-inside-thumbnail-video":[""],"post-option-inside-thumbnail-xml":["<slider-item><\/slider-item>"],"post-option-inside-thumbnail-html5-video":[""],"_thumbnail_id":["68781"],"_uag_css_file_name":["uag-css-68780.css"],"_uag_page_assets":["a:9:{s:3:\"css\";s:260:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:1:{i:0;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1778159567\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-D\u00e9cembre.jpg",620,414,false],"thumbnail":["https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-D\u00e9cembre-150x150.jpg",150,150,true],"medium":["https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-D\u00e9cembre-300x200.jpg",218,145,true],"medium_large":["https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-D\u00e9cembre.jpg",620,414,false],"large":["https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-D\u00e9cembre.jpg",620,414,false],"1536x1536":["https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-D\u00e9cembre-1536x1536.jpg",1536,1536,true],"2048x2048":["https:\/\/galapagosinformation.com\/blog\/wp-content\/uploads\/2017\/05\/Croisi\u00e8res-aux-\u00celes-Gal\u00e1pagos-en-D\u00e9cembre-2048x2048.jpg",2048,2048,true]},"uagb_author_info":{"display_name":"Nemo Galapagos Cruises","author_link":"https:\/\/galapagosinformation.com\/blog\/author\/nemogalapagoscruises\/"},"uagb_comment_info":0,"uagb_excerpt":"Les meilleurs endroits pour visiter et parcourir les incroyables \u00celes Gal\u00e1pagos.\u00a0Croisi\u00e8res aux \u00celes Gal\u00e1pagos en D\u00e9cembre. Les \u00eeles Gal\u00e1pagos sont le produit d\u2019\u00e9ruptions volcaniques en continue. Par leur localisation unique, elles ont d\u00e9velopp\u00e9 des esp\u00e8ces uniques au monde, d\u2019une richesse tr\u00e8s difficile \u00e0 croire. C\u2019est pour cela qu\u2019elles sont un des endroits favoris de tous&hellip;","_links":{"self":[{"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/posts\/68780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/comments?post=68780"}],"version-history":[{"count":0,"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/posts\/68780\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/media\/68781"}],"wp:attachment":[{"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/media?parent=68780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/categories?post=68780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/galapagosinformation.com\/blog\/wp-json\/wp\/v2\/tags?post=68780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}